{"id":54,"count":3,"description":"","link":"https:\/\/demo.qodeinteractive.com\/bridge37\/tag\/events\/","name":"Events","slug":"events","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/demo.qodeinteractive.com\/bridge37\/wp-json\/wp\/v2\/tags\/54"}],"collection":[{"href":"https:\/\/demo.qodeinteractive.com\/bridge37\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/demo.qodeinteractive.com\/bridge37\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/demo.qodeinteractive.com\/bridge37\/wp-json\/wp\/v2\/posts?tags=54"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}