{"id":10,"count":2,"description":"","link":"https:\/\/demo.qodeinteractive.com\/stockholm14\/category\/sport\/","name":"Sport","slug":"sport","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/demo.qodeinteractive.com\/stockholm14\/wp-json\/wp\/v2\/categories\/10"}],"collection":[{"href":"https:\/\/demo.qodeinteractive.com\/stockholm14\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/demo.qodeinteractive.com\/stockholm14\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/demo.qodeinteractive.com\/stockholm14\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}